{"id":27595,"date":"2023-04-27T13:17:20","date_gmt":"2023-04-27T11:17:20","guid":{"rendered":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/"},"modified":"2025-11-12T16:55:16","modified_gmt":"2025-11-12T15:55:16","slug":"leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima","status":"publish","type":"post","link":"https:\/\/www.pcabroker.com\/en\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/","title":{"rendered":"L&#8217;Europa spinge per le assicurazioni sulle catastrofi naturali legate al clima"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img decoding=\"async\"  alt=\"Ambiente-e-Assicurazione--l&#039;UE-torna-a-spingere,PCA-Consultative-Brokers\" title=\"Ambiente-e-Assicurazione\u2013l\u2019UE-torna-a-spingere,PCA-Consultative-Brokers\" src=\"https:\/\/www.pcabroker.com\/wp-content\/uploads\/2023\/06\/Ambiente-e-Assicurazione-lUE-torna-a-spingere.jpg\" \/><\/figure>\n<p class=\"old-VC-separator-transparent\">\n<p> <strong>L\u2019EIOPA<\/strong> (Autorit\u00e0 europea delle assicurazioni e delle pensioni aziendali e professionali) <strong>e la Banca centrale europea (BCE)<\/strong>\u00a0hanno pubblicato un\u00a0<a href=\"https:\/\/www.dirittobancario.it\/wp-content\/uploads\/2023\/04\/ECB-EIOPA-Climate-catastrophe-insurance.pdf\" target=\"_blank\" rel=\"noopener\"><u>documento di discussione<\/u><\/a>\u00a0congiunto su come assicurare meglio le famiglie e le imprese dell\u2019Unione europea contro le\u00a0<strong>catastrofi naturali legate al clima<\/strong>, come inondazioni o incendi.<\/p>\n<p>Le opzioni politiche illustrate nel documento mirano ad aumentare la\u00a0<strong>diffusione e l\u2019efficienza <\/strong><a href=\"https:\/\/www.dirittobancario.it\/art\/assicurazione-contro-le-catastrofi-naturali-il-documento-congiunto-eiopa-e-bce\/\" target=\"_blank\" rel=\"noopener\"><u>dell\u2019assicurazione contro le catastrofi naturali<\/u><\/a>, creando al contempo\u00a0<strong>incentivi per l\u2019adattamento e la riduzione dei rischi climatici<\/strong>.<\/p>\n<p>Gli eventi climatici e meteorologici estremi possono avere <strong>significative implicazioni macroeconomiche<\/strong>. Sebbene in Europa l&#8217;impatto economico di questi eventi sia stato storicamente contenuto, si prevede che l\u2019intensit\u00e0 aumenter\u00e0 nel tempo, dato che le catastrofi diventano sempre\u00a0pi\u00f9 frequenti e gravi a causa del riscaldamento globale.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Indice dei contenuti<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.pcabroker.com\/en\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/#LE_ASSICURAZIONI_SUL_CLIMA\" >LE ASSICURAZIONI SUL CLIMA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.pcabroker.com\/en\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/#COME_PROMUOVERE_LE_ASSICURAZIONI_SUL_CLIMA_I_CAT_BOND\" >COME PROMUOVERE LE ASSICURAZIONI SUL CLIMA: I CAT BOND<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"LE_ASSICURAZIONI_SUL_CLIMA\"><\/span><strong>LE ASSICURAZIONI SUL CLIMA<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>L&#8217;assicurazione contro le catastrofi \u00e8 uno strumento fondamentale per mitigare le perdite macroeconomiche a seguito di\u00a0eventi climatici estremi, in quanto fornisce fondi per la ricostruzione e incentiva l\u2019analisi e la riduzione del rischio.\u00a0Il costo sociale complessivo di una catastrofe dipende non solo dalla gravit\u00e0 dei danni iniziali, ma anche dalla rapidit\u00e0 con cui la ricostruzione pu\u00f2 essere completata. Tuttavia, la ricostruzione pu\u00f2 essere prolungata\u00a0e pu\u00f2 anche essere incompleta in assenza di risorse sufficienti. Da questo punto di vista <strong>i<\/strong><strong> rimborsi assicurativi riducono l&#8217;incertezza e sostengono la domanda aggregata e gli investimenti per la ricostruzione<\/strong>, consentendo alle economie di riprendersi pi\u00f9 rapidamente, limitando il periodo di stop.<\/p>\n<p>Al contrario, <strong>in assenza di assicurazione<\/strong>, le famiglie e le imprese sono costrette a\u00a0finanziare la ripresa post-catastrofe principalmente con i risparmi, il credito e\/o l&#8217;incertezza degli aiuti governativi, che con ogni probabilit\u00e0\u00a0tardano ad arrivare.\u00a0Solo circa un quarto delle perdite dovute a catastrofi climatiche \u00e8 attualmente assicurato nell&#8217;UE.\u00a0Questo gap di protezione assicurativa potrebbe aumentare nel medio-lungo termine a causa dei cambiamenti climatici, in parte perch\u00e9 la ridefinizione dei prezzi dei contratti assicurativi in risposta a eventi sempre pi\u00f9 frequenti e intensi potrebbe\u00a0rendere tali assicurazioni meno\u00a0convenienti. Ci\u00f2 aumenterebbe ulteriormente l&#8217;onere a carico dei governi, sia in termini di rischi macroeconomici che di\u00a0rischi macroeconomici ma in termini di spesa fiscale per coprire le perdite non assicurate.\u00a0Questo potrebbe aumentare gli oneri del debito pubblico e incrementare la divergenza economica tra i Paesi UE. Infatti,\u00a0<strong>l<\/strong><strong>&#8216;aumento del divario di protezione assicurativa pu\u00f2 anche comportare rischi per la stabilit\u00e0 finanziaria<\/strong>, riducendo l&#8217;erogazione di credito sia nei Paesi pi\u00f9 stabili, sia nei Paesi con grandi esposizioni del settore bancario a\u00a0eventi di rischio catastrofico.<\/p>\n<p>&nbsp;<\/p>\n<h3><span class=\"ez-toc-section\" id=\"COME_PROMUOVERE_LE_ASSICURAZIONI_SUL_CLIMA_I_CAT_BOND\"><\/span><strong>COME PROMUOVERE LE ASSICURAZIONI SUL CLIMA<\/strong><strong>: I CAT BOND<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Per\u00a0<strong>promuovere la copertura assicurativa, l\u2019EIOPA e la BCE<\/strong>\u00a0suggeriscono che le imprese di assicurazione dovrebbero definire le loro politiche per incoraggiare le famiglie e le imprese a ridurre il rischio, ad esempio concedendo sconti per l\u2019attuazione di misure efficaci di mitigazione o adattamento.<\/p>\n<p>L&#8217;assicurazione\u00a0dovrebbe essere progettata per <strong>incoraggi<\/strong><strong>are<\/strong><strong> l&#8217;adattamento e ridu<\/strong><strong>rre<\/strong><strong> nel tempo la vulnerabilit\u00e0 alle catastrofi legate al clima<\/strong>, e Il design delle\u00a0polizze assicurative pu\u00f2 fornire incentivi per la riduzione del rischio e l\u2019adattamento al climate change. A tal fine, \u00e8\u00a0anche essenziale che <strong>i (ri)assicuratori continuino a incorporare i rischi legati al cambiamento climatico nella loro gestione del rischio per garantire la sostenibilit\u00e0 a lungo termine<\/strong><strong>\u00a0<\/strong><strong>del proprio modello di business<\/strong>.\u00a0Gli strumenti del mercato dei capitali, come <strong>i <\/strong><strong>cat<\/strong><strong> bond<\/strong>, possono integrare i modelli assicurativi\u00a0per fornire liquidit\u00e0 immediata per la ricostruzione post-disastri. Inoltre, possono anche contribuire a\u00a0ridurre il tail risk assunto (il tail risk o rischio di coda \u00e8 il rischio per un bene o portafoglio di asset di registrare pi\u00f9 di 3 deviazioni standard dal prezzo corrente) dai (ri)assicuratori privati e\/o dai PPP (Public-Private-Partnership) davanti ai mercati dei capitali.<\/p>\n<p>Gli strumenti del mercato dei capitali, spesso utilizzati insieme alla riassicurazione tradizionale, offrono <strong>due vantaggi <\/strong><strong>fondamentali<\/strong>: la diversificazione sotto forma di una fonte alternativa di capitale e\u00a0 un premio pi\u00f9 basso per la copertura complessiva.\u00a0Il settore pubblico pu\u00f2 prepararsi ad affrontare le passivit\u00e0 contingenti legate alle catastrofi climatiche\u00a0migliorando la propria strategia di gestione del rischio di catastrofi ex ante. Ci\u00f2 potrebbe\u00a0sostenere il finanziamento attraverso la creazione di buffer fiscali, come i fondi di riserva nazionali.\u00a0Inoltre, potrebbe anche includere il trasferimento del rischio e misure che sostengano\u00a0soluzioni assicurative private, come schemi assicurativi pubblico-privati che raggruppano e diversificano i rischi, o prodotti del mercato dei capitali\u00a0che trasferiscono parte del rischio agli investitori.<\/p>\n<p>I governi possono sostenere e incoraggiare lo sviluppo di un mercato attivo per l&#8217;emissione e la negoziazione di cat bond, ad esempio riducendo i costi di emissione.\u00a0Una migliore misurazione delle spese fiscali legate a eventi climatici aiuterebbe anche a gestire i rischi fiscali e a garantire una migliore preparazione\u00a0prima che si verifichino i disastri \u2013 che \u00e8 poi il vero obiettivo, umano prima di tutto.<\/p>\n<p>&nbsp;<\/p>\n<p><em>PCA supporta il proprio Cliente nella\u00a0valutazione\u00a0del rischio met<\/em><em>eo, climatico e ambientale\u00a0correlato all\u2019esercizio della propria attivit\u00e0, tramite\u00a0un approfondito\u00a0checkup\u00a0ed una\u00a0consulenza analitica, che consente di\u00a0raggiungere\u00a0una corretta consapevolezza e di trasferire il rischio attraverso la\u00a0stipula di\u00a0assicurazion<\/em><em>i<\/em><em>\u00a0<\/em><em>tailor<\/em><em>-made.<\/em><\/p>\n<p><em>Per scoprire la nostra storia di innovazione e assistenza su misura del Cliente, vi invitiamo a consultare la nostra presentazione: <\/em><a href=\"https:\/\/www.pcabroker.com\/wp-content\/uploads\/20230124-PCA-Presentazione-Corporate-02.pdf\" target=\"_blank\" rel=\"noopener\"><u>link di download<\/u><\/a><em>\u00a0<\/em><\/p>\n<p><em>Siamo sempre a vostra disposizione per una valutazione preventiva del rischio della vostra azienda: basta solo <\/em><a href=\"https:\/\/www.pcabroker.com\/contatti\/\" target=\"_blank\" rel=\"noopener\"><u>contattarci<\/u><\/a><u>.<\/u><\/p>\n<p><em>Grazie per l\u2019attenzione!<\/em> <\/p>\n<p class=\"old-VC-empty_space\">\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f24899-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"24899\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/posts\/27595#wpcf7-f24899-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"24899\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f24899-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-style-3\">\n<span class=\"wpcf7-form-control-wrap titolo_pagina\" data-name=\"titolo_pagina\"><input type=\"hidden\" name=\"titolo_pagina\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"L&apos;Europa spinge per le assicurazioni sulle catastrofi naturali legate al clima\"><\/span>\n<span class=\"wpcf7-form-control-wrap URL_pagina\" data-name=\"URL_pagina\"><input type=\"hidden\" name=\"URL_pagina\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"https:\/\/www.pcabroker.com\/en\/wp-json\/wp\/v2\/posts\/27595\"><\/span>\n<span class=\"wpcf7-form-control-wrap ID_pagina\" data-name=\"ID_pagina\"><input type=\"hidden\" name=\"ID_pagina\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"27595\"><\/span>\n\t<div class=\"columns_wrap\">\n\t\t<div class=\"column-1_1\">\n\t\t\t<p><span class=\"style-line icon-name\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name e Surname\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-1_1\">\n\t\t\t<p><span class=\"style-line icon-subject\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Company\" value=\"\" type=\"text\" name=\"your-company\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-1_1\">\n\t\t\t<p><span class=\"style-line icon-phone\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-1_1\">\n\t\t\t<p><span class=\"style-line icon-email\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-1_1\">\n\t\t\t<p><span class=\"style-line icon-textarea\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"How can we help you?\" name=\"your-message\"><\/textarea><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\"><span class=\"privacy\" style=\"color:#33363c\">I have read the <a href=\"\/en\/privacy\/\" target=\"_blank\">Privacy Policy<\/a>* <\/span><\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"privacy2\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><label><input type=\"checkbox\" name=\"privacy2[]\" value=\"YES\" \/><span class=\"wpcf7-list-item-label\">YES<\/span><\/label><\/span><\/span><\/span><span class=\"privacy\" style=\"color:#33363c\">I give my consent for the purposes set out in point 2 of the <a href=\"\/en\/informative-made-to-users-of-the-website-contact-form\/\" target=\"_blank\">Informative made to users of the website contact form<\/a><\/span>\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Submit\" \/>\n\t<\/p>\n<\/div><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<p class=\"old-VC-empty_space\">\n","protected":false},"excerpt":{"rendered":"<p>L\u2019EIOPA e la BCE hanno pubblicato un documento congiunto su come assicurare meglio le famiglie e le imprese dell\u2019UE contro le catastrofi naturali legate al clima.<\/p>\n","protected":false},"author":2,"featured_media":27599,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[335,392,336],"class_list":["post-27595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-ambiente","tag-assicurazione","tag-climate-change"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ambiente e Assicurazione: l&#039;UE torna a spingere<\/title>\n<meta name=\"description\" content=\"L\u2019EIOPA e la BCE hanno pubblicato un documento congiunto su come assicurare meglio le famiglie e le imprese dell\u2019UE contro le catastrofi naturali legate al clima.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ambiente e Assicurazione: l&#039;UE torna a spingere\" \/>\n<meta property=\"og:description\" content=\"L\u2019EIOPA e la BCE hanno pubblicato un documento congiunto su come assicurare meglio le famiglie e le imprese dell\u2019UE contro le catastrofi naturali legate al clima.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/\" \/>\n<meta property=\"og:site_name\" content=\"PCA Broker\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-27T11:17:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-12T15:55:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pcabroker.com\/wp-content\/uploads\/2023\/06\/Ambiente-e-Assicurazione-lUE-torna-a-spingere-SquarePCA-Consultative-Brokers.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"649\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmaster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmaster\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\\\/\"},\"author\":{\"name\":\"webmaster\",\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/#\\\/schema\\\/person\\\/41dc9e7670d9cc3ad20b329b33cf0f08\"},\"headline\":\"L&#8217;Europa spinge per le assicurazioni sulle catastrofi naturali legate al clima\",\"datePublished\":\"2023-04-27T11:17:20+00:00\",\"dateModified\":\"2025-11-12T15:55:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\\\/\"},\"wordCount\":922,\"publisher\":{\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pcabroker.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Ambiente-e-Assicurazione-lUE-torna-a-spingere-SquarePCA-Consultative-Brokers.jpg\",\"keywords\":[\"Ambiente\",\"assicurazione\",\"Climate Change\"],\"articleSection\":[\"PCA News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\\\/\",\"url\":\"https:\\\/\\\/www.pcabroker.com\\\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\\\/\",\"name\":\"Ambiente e Assicurazione: l'UE torna a spingere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pcabroker.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Ambiente-e-Assicurazione-lUE-torna-a-spingere-SquarePCA-Consultative-Brokers.jpg\",\"datePublished\":\"2023-04-27T11:17:20+00:00\",\"dateModified\":\"2025-11-12T15:55:16+00:00\",\"description\":\"L\u2019EIOPA e la BCE hanno pubblicato un documento congiunto su come assicurare meglio le famiglie e le imprese dell\u2019UE contro le catastrofi naturali legate al clima.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pcabroker.com\\\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pcabroker.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Ambiente-e-Assicurazione-lUE-torna-a-spingere-SquarePCA-Consultative-Brokers.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pcabroker.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Ambiente-e-Assicurazione-lUE-torna-a-spingere-SquarePCA-Consultative-Brokers.jpg\",\"width\":649,\"height\":629,\"caption\":\"Ambiente-e-Assicurazione--l'UE-torna-a-spingere-Square,PCA-Consultative-Brokers.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pcabroker.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Europa spinge per le assicurazioni sulle catastrofi naturali legate al clima\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/#website\",\"url\":\"https:\\\/\\\/www.pcabroker.com\\\/\",\"name\":\"PCA Broker\",\"description\":\"Consultative Broker | Fuel your future\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pcabroker.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/#organization\",\"name\":\"PCA Broker\",\"url\":\"https:\\\/\\\/www.pcabroker.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pcabroker.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo-PCA-consultative-broker.png\",\"contentUrl\":\"https:\\\/\\\/www.pcabroker.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo-PCA-consultative-broker.png\",\"width\":370,\"height\":216,\"caption\":\"PCA Broker\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pcabroker.com\\\/#\\\/schema\\\/person\\\/41dc9e7670d9cc3ad20b329b33cf0f08\",\"name\":\"webmaster\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ambiente e Assicurazione: l'UE torna a spingere","description":"L\u2019EIOPA e la BCE hanno pubblicato un documento congiunto su come assicurare meglio le famiglie e le imprese dell\u2019UE contro le catastrofi naturali legate al clima.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/","og_locale":"en_US","og_type":"article","og_title":"Ambiente e Assicurazione: l'UE torna a spingere","og_description":"L\u2019EIOPA e la BCE hanno pubblicato un documento congiunto su come assicurare meglio le famiglie e le imprese dell\u2019UE contro le catastrofi naturali legate al clima.","og_url":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/","og_site_name":"PCA Broker","article_published_time":"2023-04-27T11:17:20+00:00","article_modified_time":"2025-11-12T15:55:16+00:00","og_image":[{"width":649,"height":629,"url":"https:\/\/www.pcabroker.com\/wp-content\/uploads\/2023\/06\/Ambiente-e-Assicurazione-lUE-torna-a-spingere-SquarePCA-Consultative-Brokers.jpg","type":"image\/jpeg"}],"author":"webmaster","twitter_card":"summary_large_image","twitter_misc":{"Written by":"webmaster","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/#article","isPartOf":{"@id":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/"},"author":{"name":"webmaster","@id":"https:\/\/www.pcabroker.com\/#\/schema\/person\/41dc9e7670d9cc3ad20b329b33cf0f08"},"headline":"L&#8217;Europa spinge per le assicurazioni sulle catastrofi naturali legate al clima","datePublished":"2023-04-27T11:17:20+00:00","dateModified":"2025-11-12T15:55:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/"},"wordCount":922,"publisher":{"@id":"https:\/\/www.pcabroker.com\/#organization"},"image":{"@id":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pcabroker.com\/wp-content\/uploads\/2023\/06\/Ambiente-e-Assicurazione-lUE-torna-a-spingere-SquarePCA-Consultative-Brokers.jpg","keywords":["Ambiente","assicurazione","Climate Change"],"articleSection":["PCA News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/","url":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/","name":"Ambiente e Assicurazione: l'UE torna a spingere","isPartOf":{"@id":"https:\/\/www.pcabroker.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/#primaryimage"},"image":{"@id":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pcabroker.com\/wp-content\/uploads\/2023\/06\/Ambiente-e-Assicurazione-lUE-torna-a-spingere-SquarePCA-Consultative-Brokers.jpg","datePublished":"2023-04-27T11:17:20+00:00","dateModified":"2025-11-12T15:55:16+00:00","description":"L\u2019EIOPA e la BCE hanno pubblicato un documento congiunto su come assicurare meglio le famiglie e le imprese dell\u2019UE contro le catastrofi naturali legate al clima.","breadcrumb":{"@id":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/#primaryimage","url":"https:\/\/www.pcabroker.com\/wp-content\/uploads\/2023\/06\/Ambiente-e-Assicurazione-lUE-torna-a-spingere-SquarePCA-Consultative-Brokers.jpg","contentUrl":"https:\/\/www.pcabroker.com\/wp-content\/uploads\/2023\/06\/Ambiente-e-Assicurazione-lUE-torna-a-spingere-SquarePCA-Consultative-Brokers.jpg","width":649,"height":629,"caption":"Ambiente-e-Assicurazione--l'UE-torna-a-spingere-Square,PCA-Consultative-Brokers.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pcabroker.com\/leuropa-spinge-per-le-assicurazioni-sulle-catastrofi-naturali-legate-al-clima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pcabroker.com\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Europa spinge per le assicurazioni sulle catastrofi naturali legate al clima"}]},{"@type":"WebSite","@id":"https:\/\/www.pcabroker.com\/#website","url":"https:\/\/www.pcabroker.com\/","name":"PCA Broker","description":"Consultative Broker | Fuel your future","publisher":{"@id":"https:\/\/www.pcabroker.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pcabroker.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.pcabroker.com\/#organization","name":"PCA Broker","url":"https:\/\/www.pcabroker.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pcabroker.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.pcabroker.com\/wp-content\/uploads\/2020\/05\/logo-PCA-consultative-broker.png","contentUrl":"https:\/\/www.pcabroker.com\/wp-content\/uploads\/2020\/05\/logo-PCA-consultative-broker.png","width":370,"height":216,"caption":"PCA Broker"},"image":{"@id":"https:\/\/www.pcabroker.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.pcabroker.com\/#\/schema\/person\/41dc9e7670d9cc3ad20b329b33cf0f08","name":"webmaster"}]}},"_links":{"self":[{"href":"https:\/\/www.pcabroker.com\/en\/wp-json\/wp\/v2\/posts\/27595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pcabroker.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pcabroker.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pcabroker.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pcabroker.com\/en\/wp-json\/wp\/v2\/comments?post=27595"}],"version-history":[{"count":1,"href":"https:\/\/www.pcabroker.com\/en\/wp-json\/wp\/v2\/posts\/27595\/revisions"}],"predecessor-version":[{"id":27598,"href":"https:\/\/www.pcabroker.com\/en\/wp-json\/wp\/v2\/posts\/27595\/revisions\/27598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pcabroker.com\/en\/wp-json\/wp\/v2\/media\/27599"}],"wp:attachment":[{"href":"https:\/\/www.pcabroker.com\/en\/wp-json\/wp\/v2\/media?parent=27595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pcabroker.com\/en\/wp-json\/wp\/v2\/categories?post=27595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pcabroker.com\/en\/wp-json\/wp\/v2\/tags?post=27595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}